{"id":3127,"name":"Edward West","url":"http:\/\/mybroadband.co.za\/news","description":"Edward is a contributor for Business Day.","link":"https:\/\/mybroadband.co.za\/news\/author\/edward-west","slug":"edward-west","meta":[],"_links":{"self":[{"href":"https:\/\/mybroadband.co.za\/news\/wp-json\/wp\/v2\/users\/3127"}],"collection":[{"href":"https:\/\/mybroadband.co.za\/news\/wp-json\/wp\/v2\/users"}]}}